{"id":10983,"date":"2023-09-13T07:00:00","date_gmt":"2023-09-13T05:00:00","guid":{"rendered":"https:\/\/irlab.se\/mfn_news\/irlab-presenterar-pa-pareto-securities-healthcare-conference-i-stockholm-den-14-september-2023\/"},"modified":"2026-05-05T22:11:42","modified_gmt":"2026-05-05T20:11:42","slug":"irlab-presenterar-pa-pareto-securities-healthcare-conference-i-stockholm-den-14-september-2023","status":"publish","type":"mfn_news","link":"https:\/\/irlab.se\/sv\/mfn_news\/irlab-presenterar-pa-pareto-securities-healthcare-conference-i-stockholm-den-14-september-2023\/","title":{"rendered":"IRLAB presenterar p\u00e5 Pareto Securities Healthcare Conference i Stockholm den 14 september 2023"},"content":{"rendered":"<div class=\"mfn-preamble\">\n<p><strong>G\u00f6teborg, Sverige, 13 september 2023 \u2013 IRLAB Therapeutics AB (Nasdaq Stockholm: IRLAB A), ett bolag som uppt\u00e4cker och utvecklar nya behandlingar vid Parkinsons sjukdom, meddelade idag att bolaget deltar p\u00e5 Pareto Securities 14e \u00e5rliga Healthcare Conference som h\u00e5lls p\u00e5 torsdag den 14 september 2023 i Stockholm.<\/strong><\/p>\n<\/div>\n<div class=\"mfn-body\">\n<p>Gunnar Olsson, vd, presenterar bolaget kl. 15:50-16:10 den 14 september 2023. Detta \u00e4r ett event som h\u00e5lls p\u00e5 Hotel At Six, Brunkebergstorg 6, Stockholm i Studio 8.<\/p>\n<p>Kontakta Pareto Securities f\u00f6r mer information om eventet.<\/p>\n<\/div>\n<div class=\"mfn-footer mfn-3931160317df\">\n<p><strong class=\"mfn-heading-1\">F\u00f6r mer information:<\/strong><\/p>\n<hr\/>\n<p>Gunnar Olsson, VD<br \/>Telefon: +46 70 576 14 02<br \/>E-mail:\u00a0<a href=\"mailto:gunnar.olsson@irlab.se\" rel=\"noopener\" target=\"_blank\">gunnar.olsson@irlab.se<\/a><\/p>\n<\/div>\n<div class=\"mfn-footer mfn-about mfn-a19a8f82b785\">\n<p><strong class=\"mfn-heading-1\">Om IRLAB<\/strong><\/p>\n<hr\/>\n<p>IRLAB uppt\u00e4cker och utvecklar en portf\u00f6lj av transformativa behandlingar f\u00f6r alla stadier av Parkinsons sjukdom. Bolaget har sitt ursprung i Nobelpristagaren Prof. Arvid Carlssons forskargrupp och uppt\u00e4ckten av ett samband mellan hj\u00e4rnans signalsubstanser och CNS-st\u00f6rningar. Mesdopetam (IRL790), under utveckling f\u00f6r behandling av levodopa-inducerade dyskinesier, har slutf\u00f6rt Fas IIb och \u00e4r i f\u00f6rberedelse f\u00f6r Fas III. Pirepemat (IRL752), befinner sig f\u00f6r n\u00e4rvarande i Fas IIb, och utv\u00e4rderas f\u00f6r sin effekt p\u00e5 balans och fallfrekvens vid Parkinson. Dessutom utvecklar bolaget \u00e4ven de tre prekliniska programmen IRL942, IRL757 och IRL1117 mot Fas I-studier. Pipelinen drivs av IRLAB:s egenutvecklade systembiologibaserade forskningsplattform Integrative Screening Process (ISP). IRLAB har sitt huvudkontor i Sverige och \u00e4r noterat p\u00e5 Nasdaq Stockholm (IRLAB A). F\u00f6r mer information, bes\u00f6k\u00a0<a href=\"http:\/\/www.irlab.se\/\" rel=\"noopener\" target=\"_blank\">www.irlab.se<\/a>.<\/p>\n<\/div>\n<div class=\"mfn-footer mfn-attachment mfn-attachment-general\">\n<p><strong class=\"mfn-heading-1\">Bifogade filer<\/strong><\/p>\n<hr\/>\n<p><a class=\"mfn-generated mfn-primary\" href=\"https:\/\/storage.mfn.se\/63b73fef-b6a8-4dda-8720-5adfaf78be68\/irlab-presenterar-pa-pareto-securities-healthcare-conference-i-stockholm-den-14-september-2023.pdf\" rel=\"noopener\" target=\"_blank\">IRLAB presenterar p\u00e5 Pareto Securities Healthcare Conference i Stockholm den 14 september 2023<\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>G\u00f6teborg, Sverige, 13 september 2023 \u2013 IRLAB Therapeutics AB (Nasdaq Stockholm: IRLAB A), ett bolag som uppt\u00e4cker och utvecklar nya behandlingar vid Parkinsons sjukdom, meddelade idag att bolaget deltar p\u00e5 Pareto Securities 14e \u00e5rliga Healthcare Conference som h\u00e5lls p\u00e5 torsdag den 14 september 2023 i Stockholm.<\/p>\n","protected":false},"template":"","class_list":["post-10983","mfn_news","type-mfn_news","status-publish","hentry","mfn-news-tag-mfn-ci_sv","mfn-news-tag-mfn-type-ir_sv","mfn-news-tag-mfn_sv","mfn-news-tag-mfn-ci-other_sv","mfn-news-tag-mfn-lang-sv_sv"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>IRLAB presenterar p\u00e5 Pareto Securities Healthcare Conference i Stockholm den 14 september 2023 - IRLAB<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/irlab.se\/sv\/mfn_news\/irlab-presenterar-pa-pareto-securities-healthcare-conference-i-stockholm-den-14-september-2023\/\" \/>\n<meta property=\"og:locale\" content=\"sv_SE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IRLAB presenterar p\u00e5 Pareto Securities Healthcare Conference i Stockholm den 14 september 2023 - IRLAB\" \/>\n<meta property=\"og:description\" content=\"G\u00f6teborg, Sverige, 13 september 2023 \u2013 IRLAB Therapeutics AB (Nasdaq Stockholm: IRLAB A), ett bolag som uppt\u00e4cker och utvecklar nya behandlingar vid Parkinsons sjukdom, meddelade idag att bolaget deltar p\u00e5 Pareto Securities 14e \u00e5rliga Healthcare Conference som h\u00e5lls p\u00e5 torsdag den 14 september 2023 i Stockholm.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/irlab.se\/sv\/mfn_news\/irlab-presenterar-pa-pareto-securities-healthcare-conference-i-stockholm-den-14-september-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"IRLAB\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-05T20:11:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Ber\u00e4knad l\u00e4stid\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/irlab.se\/sv\/mfn_news\/irlab-presenterar-pa-pareto-securities-healthcare-conference-i-stockholm-den-14-september-2023\/\",\"url\":\"https:\/\/irlab.se\/sv\/mfn_news\/irlab-presenterar-pa-pareto-securities-healthcare-conference-i-stockholm-den-14-september-2023\/\",\"name\":\"IRLAB presenterar p\u00e5 Pareto Securities Healthcare Conference i Stockholm den 14 september 2023 - IRLAB\",\"isPartOf\":{\"@id\":\"https:\/\/irlab.se\/#website\"},\"datePublished\":\"2023-09-13T05:00:00+00:00\",\"dateModified\":\"2026-05-05T20:11:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/irlab.se\/sv\/mfn_news\/irlab-presenterar-pa-pareto-securities-healthcare-conference-i-stockholm-den-14-september-2023\/#breadcrumb\"},\"inLanguage\":\"sv-SE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/irlab.se\/sv\/mfn_news\/irlab-presenterar-pa-pareto-securities-healthcare-conference-i-stockholm-den-14-september-2023\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/irlab.se\/sv\/mfn_news\/irlab-presenterar-pa-pareto-securities-healthcare-conference-i-stockholm-den-14-september-2023\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/irlab.se\/sv\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MFN News Items\",\"item\":\"https:\/\/irlab.se\/sv\/pressmeddelanden\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"IRLAB presenterar p\u00e5 Pareto Securities Healthcare Conference i Stockholm den 14 september 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/irlab.se\/#website\",\"url\":\"https:\/\/irlab.se\/\",\"name\":\"Irlab\",\"description\":\"Novel treatments for Parkinson&#039;s disease\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/irlab.se\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sv-SE\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IRLAB presenterar p\u00e5 Pareto Securities Healthcare Conference i Stockholm den 14 september 2023 - IRLAB","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/irlab.se\/sv\/mfn_news\/irlab-presenterar-pa-pareto-securities-healthcare-conference-i-stockholm-den-14-september-2023\/","og_locale":"sv_SE","og_type":"article","og_title":"IRLAB presenterar p\u00e5 Pareto Securities Healthcare Conference i Stockholm den 14 september 2023 - IRLAB","og_description":"G\u00f6teborg, Sverige, 13 september 2023 \u2013 IRLAB Therapeutics AB (Nasdaq Stockholm: IRLAB A), ett bolag som uppt\u00e4cker och utvecklar nya behandlingar vid Parkinsons sjukdom, meddelade idag att bolaget deltar p\u00e5 Pareto Securities 14e \u00e5rliga Healthcare Conference som h\u00e5lls p\u00e5 torsdag den 14 september 2023 i Stockholm.","og_url":"https:\/\/irlab.se\/sv\/mfn_news\/irlab-presenterar-pa-pareto-securities-healthcare-conference-i-stockholm-den-14-september-2023\/","og_site_name":"IRLAB","article_modified_time":"2026-05-05T20:11:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Ber\u00e4knad l\u00e4stid":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/irlab.se\/sv\/mfn_news\/irlab-presenterar-pa-pareto-securities-healthcare-conference-i-stockholm-den-14-september-2023\/","url":"https:\/\/irlab.se\/sv\/mfn_news\/irlab-presenterar-pa-pareto-securities-healthcare-conference-i-stockholm-den-14-september-2023\/","name":"IRLAB presenterar p\u00e5 Pareto Securities Healthcare Conference i Stockholm den 14 september 2023 - IRLAB","isPartOf":{"@id":"https:\/\/irlab.se\/#website"},"datePublished":"2023-09-13T05:00:00+00:00","dateModified":"2026-05-05T20:11:42+00:00","breadcrumb":{"@id":"https:\/\/irlab.se\/sv\/mfn_news\/irlab-presenterar-pa-pareto-securities-healthcare-conference-i-stockholm-den-14-september-2023\/#breadcrumb"},"inLanguage":"sv-SE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/irlab.se\/sv\/mfn_news\/irlab-presenterar-pa-pareto-securities-healthcare-conference-i-stockholm-den-14-september-2023\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/irlab.se\/sv\/mfn_news\/irlab-presenterar-pa-pareto-securities-healthcare-conference-i-stockholm-den-14-september-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/irlab.se\/sv\/"},{"@type":"ListItem","position":2,"name":"MFN News Items","item":"https:\/\/irlab.se\/sv\/pressmeddelanden\/"},{"@type":"ListItem","position":3,"name":"IRLAB presenterar p\u00e5 Pareto Securities Healthcare Conference i Stockholm den 14 september 2023"}]},{"@type":"WebSite","@id":"https:\/\/irlab.se\/#website","url":"https:\/\/irlab.se\/","name":"Irlab","description":"Novel treatments for Parkinson&#039;s disease","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/irlab.se\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sv-SE"}]}},"_links":{"self":[{"href":"https:\/\/irlab.se\/sv\/wp-json\/wp\/v2\/mfn_news\/10983","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/irlab.se\/sv\/wp-json\/wp\/v2\/mfn_news"}],"about":[{"href":"https:\/\/irlab.se\/sv\/wp-json\/wp\/v2\/types\/mfn_news"}],"wp:attachment":[{"href":"https:\/\/irlab.se\/sv\/wp-json\/wp\/v2\/media?parent=10983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}